{"id":7748,"date":"2026-02-04T18:29:16","date_gmt":"2026-02-04T17:29:16","guid":{"rendered":"https:\/\/bk-hammer.com\/?page_id=7748"},"modified":"2026-07-08T11:29:09","modified_gmt":"2026-07-08T09:29:09","slug":"1-2-t","status":"publish","type":"page","link":"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/1-2-t\/","title":{"rendered":"1-2 T"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"7748\" class=\"elementor elementor-7748\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f888d03 e-con-full e-flex e-con e-parent\" data-id=\"3f888d03\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-228e3412 e-con-full e-flex e-con e-child\" data-id=\"228e3412\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7398c606 elementor-widget elementor-widget-theme-site-logo elementor-widget-image\" data-id=\"7398c606\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/bk-hammer.com\/de\/startseite\/\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2025\/12\/bk-hammer_logo.svg\" title=\"bk-hammer_logo\" alt=\"bk-hammer_logo\" loading=\"lazy\" \/>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-654d9128 e-con-full e-flex e-con e-child\" data-id=\"654d9128\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7dbb5b35 elementor-nav-menu__align-end elementor-nav-menu--dropdown-mobile elementor-nav-menu--stretch elementor-nav-menu__text-align-center elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"7dbb5b35\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-7dbb5b35\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-240\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/\" class=\"elementor-item\">Produkte<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-239\"><a href=\"https:\/\/bk-hammer.com\/de\/kontakt\/\" class=\"elementor-item\">Kontakt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-238\"><a href=\"https:\/\/bk-hammer.com\/de\/o-nas\/\" class=\"elementor-item\">\u00dcber uns<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7dbb5b35\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-240\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/\" class=\"elementor-item\" tabindex=\"-1\">Produkte<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-239\"><a href=\"https:\/\/bk-hammer.com\/de\/kontakt\/\" class=\"elementor-item\" tabindex=\"-1\">Kontakt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-238\"><a href=\"https:\/\/bk-hammer.com\/de\/o-nas\/\" class=\"elementor-item\" tabindex=\"-1\">\u00dcber uns<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-479d5f8f e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"479d5f8f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7104ab9c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7104ab9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#szukaj\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewbox=\"0 0 15 15\" fill=\"none\"><ellipse cx=\"6.33507\" cy=\"6.21428\" rx=\"5.33507\" ry=\"5.21428\" stroke=\"#FF5800\" stroke-width=\"1.5\" stroke-linecap=\"square\"><\/ellipse><path d=\"M9.97754 10.0542L12.9996 13.0002\" stroke=\"#FF5800\" stroke-width=\"1.5\" stroke-linecap=\"square\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-55fec687 e-con-full e-flex e-con e-parent\" data-id=\"55fec687\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c81c4e7 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"1c81c4e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">L\u00f6ffel 1-2 T<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59a92e3 e-con-full e-flex e-con e-parent\" data-id=\"59a92e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-73c1bc7b e-flex e-con-boxed e-con e-child\" data-id=\"73c1bc7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2523e472 elementor-nav-menu__align-center elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"2523e472\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-2523e472\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-732\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/polecane\/\" class=\"elementor-item\">Empfohlen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-731\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/bestsellery\/\" class=\"elementor-item\">Bestseller<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4263\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/szczeki-kruszace\/\" class=\"elementor-item\">Kieferbrecher<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-730\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/mloty\/\" class=\"elementor-item\">H\u00e4mmer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-729\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/chwytaki\/\" class=\"elementor-item\">Greifer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-728\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/mulczery\/\" class=\"elementor-item\">Maulbeeren<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-723\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/szczeki\/\" class=\"elementor-item\">Kiefer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-727\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/szybkozlacza\/\" class=\"elementor-item\">Schnellkupplungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3949\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/powertilt\/\" class=\"elementor-item\">Powertilt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9280\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/rototilt\/\" class=\"elementor-item\">Rototilt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-726\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/widly\/\" class=\"elementor-item\">Heugabel<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-725\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/zageszczarki\/\" class=\"elementor-item\">Verdichter<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-724\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/kosze\/\" class=\"elementor-item\">K\u00f6rbe<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6860\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/frezarki\/\" class=\"elementor-item\">Fr\u00e4smaschinen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7069\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/wiertnice\/\" class=\"elementor-item\">Bohrgest\u00e4nge<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-7740\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/\" class=\"elementor-item\">L\u00f6ffel<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-9496\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/1-2-t\/\" class=\"elementor-sub-item\">1-2 T<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9499\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/1-2-t\/1-2-t-jcb\/\" class=\"elementor-sub-item\">JCB<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9501\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/1-2-t\/1-2-t-cat\/\" class=\"elementor-sub-item\">Katze<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9503\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/1-2-t\/1-2-t-ms01\/\" class=\"elementor-sub-item\">MS01<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-9497\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/25-4-t\/\" class=\"elementor-sub-item\">2,5-4 T<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9500\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/25-4-t\/25-4-jcb\/\" class=\"elementor-sub-item\">JCB<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9502\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/25-4-t\/25-4-cat\/\" class=\"elementor-sub-item\">Katze<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9498\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/4-8-t\/\" class=\"elementor-sub-item\">4-8 T<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9153\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki-przesiewajace\/\" class=\"elementor-item\">Siebl\u00f6ffel<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-2523e472\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-732\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/polecane\/\" class=\"elementor-item\" tabindex=\"-1\">Empfohlen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-731\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/bestsellery\/\" class=\"elementor-item\" tabindex=\"-1\">Bestseller<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4263\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/szczeki-kruszace\/\" class=\"elementor-item\" tabindex=\"-1\">Kieferbrecher<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-730\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/mloty\/\" class=\"elementor-item\" tabindex=\"-1\">H\u00e4mmer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-729\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/chwytaki\/\" class=\"elementor-item\" tabindex=\"-1\">Greifer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-728\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/mulczery\/\" class=\"elementor-item\" tabindex=\"-1\">Maulbeeren<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-723\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/szczeki\/\" class=\"elementor-item\" tabindex=\"-1\">Kiefer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-727\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/szybkozlacza\/\" class=\"elementor-item\" tabindex=\"-1\">Schnellkupplungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3949\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/powertilt\/\" class=\"elementor-item\" tabindex=\"-1\">Powertilt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9280\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/rototilt\/\" class=\"elementor-item\" tabindex=\"-1\">Rototilt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-726\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/widly\/\" class=\"elementor-item\" tabindex=\"-1\">Heugabel<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-725\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/zageszczarki\/\" class=\"elementor-item\" tabindex=\"-1\">Verdichter<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-724\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/kosze\/\" class=\"elementor-item\" tabindex=\"-1\">K\u00f6rbe<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6860\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/frezarki\/\" class=\"elementor-item\" tabindex=\"-1\">Fr\u00e4smaschinen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7069\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/wiertnice\/\" class=\"elementor-item\" tabindex=\"-1\">Bohrgest\u00e4nge<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-7740\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/\" class=\"elementor-item\" tabindex=\"-1\">L\u00f6ffel<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-9496\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/1-2-t\/\" class=\"elementor-sub-item\" tabindex=\"-1\">1-2 T<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9499\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/1-2-t\/1-2-t-jcb\/\" class=\"elementor-sub-item\" tabindex=\"-1\">JCB<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9501\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/1-2-t\/1-2-t-cat\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Katze<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9503\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/1-2-t\/1-2-t-ms01\/\" class=\"elementor-sub-item\" tabindex=\"-1\">MS01<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-9497\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/25-4-t\/\" class=\"elementor-sub-item\" tabindex=\"-1\">2,5-4 T<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9500\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/25-4-t\/25-4-jcb\/\" class=\"elementor-sub-item\" tabindex=\"-1\">JCB<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9502\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/25-4-t\/25-4-cat\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Katze<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9498\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki\/4-8-t\/\" class=\"elementor-sub-item\" tabindex=\"-1\">4-8 T<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9153\"><a href=\"https:\/\/bk-hammer.com\/de\/produkty\/lyzki-przesiewajace\/\" class=\"elementor-item\" tabindex=\"-1\">Siebl\u00f6ffel<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6584a638 e-con-full e-flex e-con e-parent\" data-id=\"6584a638\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4406a109 e-con-full e-flex e-con e-child\" data-id=\"4406a109\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-322edeab e-con-full e-flex e-con e-child\" data-id=\"322edeab\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34870663 elementor-widget elementor-widget-image\" data-id=\"34870663\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/1-2-t\/lyzka-kopiaca-jcb-mini-25\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7799\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50de0c5a e-con-full e-flex e-con e-child\" data-id=\"50de0c5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-204c476 elementor-widget elementor-widget-heading\" data-id=\"204c476\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">JCB Mini Bagger Schaufel 25<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44884a48 elementor-widget elementor-widget-heading\" data-id=\"44884a48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ba7b4f9 elementor-widget elementor-widget-heading\" data-id=\"6ba7b4f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">690,00 z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0594a9f e-con-full e-flex e-con e-child\" data-id=\"0594a9f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60952a8 elementor-widget elementor-widget-image\" data-id=\"60952a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/lyzka-kopiaca-cat-mini-25\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-25-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7914\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-25-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-25-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-25-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-25-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-25-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-25-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-25-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7da412 e-con-full e-flex e-con e-child\" data-id=\"f7da412\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c64c75 elementor-widget elementor-widget-heading\" data-id=\"3c64c75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">CAT Mini-Schaufel 25<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf2b840 elementor-widget elementor-widget-heading\" data-id=\"cf2b840\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1fc384 elementor-widget elementor-widget-heading\" data-id=\"d1fc384\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">690,00 z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2280c82 e-con-full e-flex e-con e-child\" data-id=\"2280c82\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee3e2c6 elementor-widget elementor-widget-image\" data-id=\"ee3e2c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/1-2-t\/hydraulikbagger-jcb-mini-30\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-30-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7810\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-30-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-30-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-30-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-30-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-30-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-30-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-30-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dbc60a2 e-con-full e-flex e-con e-child\" data-id=\"dbc60a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61fb3aa elementor-widget elementor-widget-heading\" data-id=\"61fb3aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">JCB Mini-Baggerl\u00f6ffel 30<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5e2a4f elementor-widget elementor-widget-heading\" data-id=\"c5e2a4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34430d2 elementor-widget elementor-widget-heading\" data-id=\"34430d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">720,00 z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7d1d51 e-con-full e-flex e-con e-child\" data-id=\"b7d1d51\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f35a134 elementor-widget elementor-widget-image\" data-id=\"f35a134\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/lyzka-kopiaca-cat-mini-30\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-30-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7927\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-30-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-30-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-30-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-30-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-30-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-30-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-30-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a31523c e-con-full e-flex e-con e-child\" data-id=\"a31523c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1557ee8 elementor-widget elementor-widget-heading\" data-id=\"1557ee8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">CAT Mini-Schaufel 30<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba1d421 elementor-widget elementor-widget-heading\" data-id=\"ba1d421\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1401f77 elementor-widget elementor-widget-heading\" data-id=\"1401f77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">720,00 z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d96d312 e-con-full e-flex e-con e-child\" data-id=\"d96d312\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d39a78c elementor-widget elementor-widget-image\" data-id=\"d39a78c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/1-2-t\/jcb-minibagger-35\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-35-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7822\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-35-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-35-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-35-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-35-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-35-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-35-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-35-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b0fdc8 e-con-full e-flex e-con e-child\" data-id=\"4b0fdc8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dda88c8 elementor-widget elementor-widget-heading\" data-id=\"dda88c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">JCB Mini 35 Schaufel<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ddae51 elementor-widget elementor-widget-heading\" data-id=\"1ddae51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6919275 elementor-widget elementor-widget-heading\" data-id=\"6919275\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">740,00 z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7a893f e-con-full e-flex e-con e-child\" data-id=\"e7a893f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d19666 elementor-widget elementor-widget-image\" data-id=\"1d19666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/__geloscht\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-35-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7940\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-35-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-35-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-35-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-35-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-35-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-35-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-35-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-441c137 e-con-full e-flex e-con e-child\" data-id=\"441c137\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-398c84c elementor-widget elementor-widget-heading\" data-id=\"398c84c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">CAT Mini-Baggerschaufel 35<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba52e18 elementor-widget elementor-widget-heading\" data-id=\"ba52e18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e30ccec elementor-widget elementor-widget-heading\" data-id=\"e30ccec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">740,00 z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a249109 e-con-full e-flex e-con e-child\" data-id=\"a249109\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-613ae1a elementor-widget elementor-widget-image\" data-id=\"613ae1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/1-2-t\/minibagger-jcb-40\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-40-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7832\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-40-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-40-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-40-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-40-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-40-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-40-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-40-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d22ab02 e-con-full e-flex e-con e-child\" data-id=\"d22ab02\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c4ce3b elementor-widget elementor-widget-heading\" data-id=\"6c4ce3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Schaufel JCB Minibagger 40<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c619f6f elementor-widget elementor-widget-heading\" data-id=\"c619f6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0d53a1 elementor-widget elementor-widget-heading\" data-id=\"a0d53a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">790,00 z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af77d4f e-con-full e-flex e-con e-child\" data-id=\"af77d4f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb37fa8 elementor-widget elementor-widget-image\" data-id=\"fb37fa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/lyzka-kopiaca-cat-mini-40\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-40-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7947\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-40-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-40-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-40-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-40-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-40-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-40-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-40-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ad9167 e-con-full e-flex e-con e-child\" data-id=\"6ad9167\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34e3e94 elementor-widget elementor-widget-heading\" data-id=\"34e3e94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">CAT Mini-Schaufel 40<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9294bb9 elementor-widget elementor-widget-heading\" data-id=\"9294bb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0791434 elementor-widget elementor-widget-heading\" data-id=\"0791434\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">790,00 z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-732fb12 e-con-full e-flex e-con e-child\" data-id=\"732fb12\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77dc4fd elementor-widget elementor-widget-image\" data-id=\"77dc4fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/1-2-t\/jcb-minibagger-45\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-45-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7839\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-45-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-45-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-45-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-45-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-45-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-45-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-45-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5285f0a e-con-full e-flex e-con e-child\" data-id=\"5285f0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bdd9d93 elementor-widget elementor-widget-heading\" data-id=\"bdd9d93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">JCB Mini-Schaufel 45<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85ec5ad elementor-widget elementor-widget-heading\" data-id=\"85ec5ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f50134 elementor-widget elementor-widget-heading\" data-id=\"9f50134\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">830,00 z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3640f7b e-con-full e-flex e-con e-child\" data-id=\"3640f7b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c67bae elementor-widget elementor-widget-image\" data-id=\"2c67bae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/lyzka-kopiaca-cat-mini-45\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-45-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7958\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-45-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-45-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-45-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-45-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-45-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-45-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-45-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-155bac1 e-con-full e-flex e-con e-child\" data-id=\"155bac1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e74a89b elementor-widget elementor-widget-heading\" data-id=\"e74a89b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">CAT Mini-Schaufel<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88d5c6f elementor-widget elementor-widget-heading\" data-id=\"88d5c6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1538f0f elementor-widget elementor-widget-heading\" data-id=\"1538f0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">830,00 z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-014f77c e-con-full e-flex e-con e-child\" data-id=\"014f77c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60aa881 elementor-widget elementor-widget-image\" data-id=\"60aa881\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/1-2-t\/minibagger-jcb-50\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-50-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7846\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-50-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-50-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-50-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-50-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-50-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-50-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-50-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-777d542 e-con-full e-flex e-con e-child\" data-id=\"777d542\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d268718 elementor-widget elementor-widget-heading\" data-id=\"d268718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Mini-Baggerl\u00f6ffel JCB 50<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94d1426 elementor-widget elementor-widget-heading\" data-id=\"94d1426\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c9f0fb elementor-widget elementor-widget-heading\" data-id=\"9c9f0fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">870,00 z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68e2e44 e-con-full e-flex e-con e-child\" data-id=\"68e2e44\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2704843 elementor-widget elementor-widget-image\" data-id=\"2704843\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/lyzka-kopaca-kat-mini-50\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-50-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7968\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-50-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-50-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-50-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-50-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-50-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-50-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-50-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5762363 e-con-full e-flex e-con e-child\" data-id=\"5762363\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75c35c0 elementor-widget elementor-widget-heading\" data-id=\"75c35c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Mini-Schaufel CAT 50<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62f12a8 elementor-widget elementor-widget-heading\" data-id=\"62f12a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-998f5d1 elementor-widget elementor-widget-heading\" data-id=\"998f5d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">870,00 z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9fc1c8e e-con-full e-flex e-con e-child\" data-id=\"9fc1c8e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d9a6ddd elementor-widget elementor-widget-image\" data-id=\"d9a6ddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/1-2-t\/minibagger-jcb-60\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-60-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7853\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-60-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-60-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-60-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-60-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-60-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-60-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-60-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef10835 e-con-full e-flex e-con e-child\" data-id=\"ef10835\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7240a48 elementor-widget elementor-widget-heading\" data-id=\"7240a48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">L\u00f6ffelbagger JCB mini 60<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9376721 elementor-widget elementor-widget-heading\" data-id=\"9376721\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-984318f elementor-widget elementor-widget-heading\" data-id=\"984318f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">950,00\u00a0z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d0bddd e-con-full e-flex e-con e-child\" data-id=\"4d0bddd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f292d8 elementor-widget elementor-widget-image\" data-id=\"6f292d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/lyzka-kopiaca-cat-mini-60\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"580\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-60-01-1024x1024.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7978\" alt=\"\" srcset=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-60-01-1024x1024.png 1024w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-60-01-300x300.png 300w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-60-01-150x150.png 150w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-60-01-768x768.png 768w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-60-01-1536x1536.png 1536w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-60-01-1200x1200.png 1200w, https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/CAT-Mini-60-01.png 1960w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb6ce59 e-con-full e-flex e-con e-child\" data-id=\"eb6ce59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-739ee1e elementor-widget elementor-widget-heading\" data-id=\"739ee1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">CAT Minibagger L\u00f6ffel 60<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-038bbd3 elementor-widget elementor-widget-heading\" data-id=\"038bbd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maschinen 1-2 T<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8cc797 elementor-widget elementor-widget-heading\" data-id=\"c8cc797\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">950,00\u00a0z\u0142<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-160524a8 e-con-full e-flex e-con e-parent\" data-id=\"160524a8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f004f9b e-con-full e-flex e-con e-parent\" data-id=\"7f004f9b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-432d0fee e-con-full e-flex e-con e-child\" data-id=\"432d0fee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36a72ba2 elementor-widget elementor-widget-theme-site-logo elementor-widget-image\" data-id=\"36a72ba2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/bk-hammer.com\/de\/startseite\/\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2025\/12\/bk-hammer_logo.svg\" title=\"bk-hammer_logo\" alt=\"bk-hammer_logo\" loading=\"lazy\" \/>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39bd0e42 elementor-widget elementor-widget-text-editor\" data-id=\"39bd0e42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vertrieb von professionellen<br \/>Abbruchausr\u00fcstung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3515955a e-con-full e-flex e-con e-child\" data-id=\"3515955a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c83f955 elementor-widget elementor-widget-heading\" data-id=\"2c83f955\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/bk-hammer.com\/de\/startseite\/\">Startseite<\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5753056e elementor-widget elementor-widget-heading\" data-id=\"5753056e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/bk-hammer.com\/de\/produkte\/\">Produkte<\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bce5ae0 elementor-widget elementor-widget-heading\" data-id=\"4bce5ae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/bk-hammer.com\/de\/kontakt\/\">Kontakt<\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fe06cd4 elementor-widget elementor-widget-heading\" data-id=\"7fe06cd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/bk-hammer.com\/de\/uber-uns\/\">\u00dcber uns<\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a06c210 e-con-full e-flex e-con e-child\" data-id=\"a06c210\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45332d21 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-search\" data-id=\"45332d21\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submit_trigger&quot;:&quot;key_enter&quot;,&quot;pagination_type_options&quot;:&quot;none&quot;}\" data-widget_type=\"search.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<search class=\"e-search hidden\" role=\"search\">\n\t\t\t<form class=\"e-search-form\" action=\"https:\/\/bk-hammer.com\/de\/\" method=\"get\" data-trp-original-action=\"https:\/\/bk-hammer.com\/de\">\n\n\t\t\t\t\n\t\t\t\t<label class=\"e-search-label\" for=\"search-45332d21\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">\n\t\t\t\t\t\tSuche\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/label>\n\n\t\t\t\t<div class=\"e-search-input-wrapper\">\n\t\t\t\t\t<input id=\"search-45332d21\" placeholder=\"Suchen Sie...\" class=\"e-search-input\" type=\"search\" name=\"s\" value=\"\" autocomplete=\"off\" role=\"combobox\" aria-autocomplete=\"list\" aria-expanded=\"false\" aria-controls=\"results-45332d21\" aria-haspopup=\"listbox\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<output id=\"results-45332d21\" class=\"e-search-results-container hide-loader\" aria-live=\"polite\" aria-atomic=\"true\" aria-label=\"Ergebnisse f\u00fcr Suche\" tabindex=\"0\">\n\t\t\t\t\t\t<div class=\"e-search-results\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/output>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<button class=\"e-search-submit elementor-screen-only\" type=\"submit\" aria-label=\"Suche\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t<input type=\"hidden\" name=\"e_search_props\" value=\"45332d21-7748\">\n\t\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form>\n\t\t<\/search>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4582437e elementor-widget elementor-widget-menu-anchor\" data-id=\"4582437e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"szukaj\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58e68d49 e-con-full e-flex e-con e-child\" data-id=\"58e68d49\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78a70091 e-con-full e-flex e-con e-child\" data-id=\"78a70091\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a21ec61 e-con-full e-flex e-con e-child\" data-id=\"1a21ec61\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e1bdbb e-con-full e-flex e-con e-child\" data-id=\"3e1bdbb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f4049fa elementor-shape-circle e-grid-align-right elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"7f4049fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-56fe5e8\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-ad0c8ce\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-e82b1f3\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3929be12 e-con-full e-flex e-con e-child\" data-id=\"3929be12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f7ecd7a elementor-widget elementor-widget-text-editor\" data-id=\"4f7ecd7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-decoration: underline;\"><a href=\"http:\/\/bk-hammer.com\/de\/\">bk-hammer.com<\/a><\/span> \u00a9 2026 Alle Rechte vorbehalten. Design und Umsetzung <span style=\"text-decoration: underline;\"><a href=\"http:\/\/patt-bielicka.pl\">patt-bielicka.pl<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0141y\u017cki 1-2 T \u0141y\u017cka Kopi\u0105ca JCB mini 25 maszyny 1-2 T 690,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca CAT mini 25 maszyny 1-2 T 690,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca JCB mini 30 maszyny 1-2 T 720,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca CAT mini 30 maszyny 1-2 T 720,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca JCB mini 35 maszyny 1-2 T 740,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca CAT mini 35 maszyny 1-2 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":7732,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-7748","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1-2 T - bk-hammer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/1-2-t\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1-2 T - bk-hammer\" \/>\n<meta property=\"og:description\" content=\"\u0141y\u017cki 1-2 T \u0141y\u017cka Kopi\u0105ca JCB mini 25 maszyny 1-2 T 690,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca CAT mini 25 maszyny 1-2 T 690,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca JCB mini 30 maszyny 1-2 T 720,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca CAT mini 30 maszyny 1-2 T 720,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca JCB mini 35 maszyny 1-2 T 740,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca CAT mini 35 maszyny 1-2 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/1-2-t\/\" \/>\n<meta property=\"og:site_name\" content=\"bk-hammer\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T09:29:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1960\" \/>\n\t<meta property=\"og:image:height\" content=\"1960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bk-hammer.com\\\/produkty\\\/lyzki\\\/1-2-t\\\/\",\"url\":\"https:\\\/\\\/bk-hammer.com\\\/produkty\\\/lyzki\\\/1-2-t\\\/\",\"name\":\"1-2 T - bk-hammer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bk-hammer.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bk-hammer.com\\\/produkty\\\/lyzki\\\/1-2-t\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bk-hammer.com\\\/produkty\\\/lyzki\\\/1-2-t\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bk-hammer.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/JCB-Mini-25-01-1024x1024.png\",\"datePublished\":\"2026-02-04T17:29:16+00:00\",\"dateModified\":\"2026-07-08T09:29:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bk-hammer.com\\\/produkty\\\/lyzki\\\/1-2-t\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bk-hammer.com\\\/produkty\\\/lyzki\\\/1-2-t\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bk-hammer.com\\\/produkty\\\/lyzki\\\/1-2-t\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bk-hammer.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/JCB-Mini-25-01-1024x1024.png\",\"contentUrl\":\"https:\\\/\\\/bk-hammer.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/JCB-Mini-25-01-1024x1024.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bk-hammer.com\\\/produkty\\\/lyzki\\\/1-2-t\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bk-hammer.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkty\",\"item\":\"https:\\\/\\\/bk-hammer.com\\\/produkty\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0141y\u017cki\",\"item\":\"https:\\\/\\\/bk-hammer.com\\\/produkty\\\/lyzki\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"1-2 T\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bk-hammer.com\\\/#website\",\"url\":\"https:\\\/\\\/bk-hammer.com\\\/\",\"name\":\"bk-hammer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bk-hammer.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bk-hammer.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bk-hammer.com\\\/#organization\",\"name\":\"bk-hammer\",\"url\":\"https:\\\/\\\/bk-hammer.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bk-hammer.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bk-hammer.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/bk-hammer_logo.svg\",\"contentUrl\":\"https:\\\/\\\/bk-hammer.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/bk-hammer_logo.svg\",\"width\":326,\"height\":40,\"caption\":\"bk-hammer\"},\"image\":{\"@id\":\"https:\\\/\\\/bk-hammer.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1-2 T - bk-hammer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/1-2-t\/","og_locale":"de_DE","og_type":"article","og_title":"1-2 T - bk-hammer","og_description":"\u0141y\u017cki 1-2 T \u0141y\u017cka Kopi\u0105ca JCB mini 25 maszyny 1-2 T 690,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca CAT mini 25 maszyny 1-2 T 690,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca JCB mini 30 maszyny 1-2 T 720,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca CAT mini 30 maszyny 1-2 T 720,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca JCB mini 35 maszyny 1-2 T 740,00\u00a0z\u0142 \u0141y\u017cka Kopi\u0105ca CAT mini 35 maszyny 1-2 [&hellip;]","og_url":"https:\/\/bk-hammer.com\/de\/produkte\/lyzkis\/1-2-t\/","og_site_name":"bk-hammer","article_modified_time":"2026-07-08T09:29:09+00:00","og_image":[{"width":1960,"height":1960,"url":"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bk-hammer.com\/produkty\/lyzki\/1-2-t\/","url":"https:\/\/bk-hammer.com\/produkty\/lyzki\/1-2-t\/","name":"1-2 T - bk-hammer","isPartOf":{"@id":"https:\/\/bk-hammer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bk-hammer.com\/produkty\/lyzki\/1-2-t\/#primaryimage"},"image":{"@id":"https:\/\/bk-hammer.com\/produkty\/lyzki\/1-2-t\/#primaryimage"},"thumbnailUrl":"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01-1024x1024.png","datePublished":"2026-02-04T17:29:16+00:00","dateModified":"2026-07-08T09:29:09+00:00","breadcrumb":{"@id":"https:\/\/bk-hammer.com\/produkty\/lyzki\/1-2-t\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bk-hammer.com\/produkty\/lyzki\/1-2-t\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bk-hammer.com\/produkty\/lyzki\/1-2-t\/#primaryimage","url":"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01-1024x1024.png","contentUrl":"https:\/\/bk-hammer.com\/wp-content\/uploads\/2026\/02\/JCB-Mini-25-01-1024x1024.png"},{"@type":"BreadcrumbList","@id":"https:\/\/bk-hammer.com\/produkty\/lyzki\/1-2-t\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bk-hammer.com\/"},{"@type":"ListItem","position":2,"name":"Produkty","item":"https:\/\/bk-hammer.com\/produkty\/"},{"@type":"ListItem","position":3,"name":"\u0141y\u017cki","item":"https:\/\/bk-hammer.com\/produkty\/lyzki\/"},{"@type":"ListItem","position":4,"name":"1-2 T"}]},{"@type":"WebSite","@id":"https:\/\/bk-hammer.com\/#website","url":"https:\/\/bk-hammer.com\/","name":"bk-Hammer","description":"","publisher":{"@id":"https:\/\/bk-hammer.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bk-hammer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/bk-hammer.com\/#organization","name":"bk-Hammer","url":"https:\/\/bk-hammer.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bk-hammer.com\/#\/schema\/logo\/image\/","url":"https:\/\/bk-hammer.com\/wp-content\/uploads\/2025\/12\/bk-hammer_logo.svg","contentUrl":"https:\/\/bk-hammer.com\/wp-content\/uploads\/2025\/12\/bk-hammer_logo.svg","width":326,"height":40,"caption":"bk-hammer"},"image":{"@id":"https:\/\/bk-hammer.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bk-hammer.com\/de\/wp-json\/wp\/v2\/pages\/7748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bk-hammer.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bk-hammer.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bk-hammer.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bk-hammer.com\/de\/wp-json\/wp\/v2\/comments?post=7748"}],"version-history":[{"count":37,"href":"https:\/\/bk-hammer.com\/de\/wp-json\/wp\/v2\/pages\/7748\/revisions"}],"predecessor-version":[{"id":9521,"href":"https:\/\/bk-hammer.com\/de\/wp-json\/wp\/v2\/pages\/7748\/revisions\/9521"}],"up":[{"embeddable":true,"href":"https:\/\/bk-hammer.com\/de\/wp-json\/wp\/v2\/pages\/7732"}],"wp:attachment":[{"href":"https:\/\/bk-hammer.com\/de\/wp-json\/wp\/v2\/media?parent=7748"}],"curies":[{"name":"WordPress","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}